{"id":642,"date":"2013-05-23T22:01:07","date_gmt":"2013-05-23T22:01:07","guid":{"rendered":"http:\/\/revistazo.com\/content\/?p=642"},"modified":"2013-05-23T22:01:07","modified_gmt":"2013-05-23T22:01:07","slug":"los-mismos-que-violaron-los-derechos-humanos-durante-el-golpe-de-estado-lo-hicieron-en-los-80","status":"publish","type":"post","link":"https:\/\/revistazo.com\/content\/los-mismos-que-violaron-los-derechos-humanos-durante-el-golpe-de-estado-lo-hicieron-en-los-80\/","title":{"rendered":"\u201cLos mismos que violaron los Derechos Humanos durante el Golpe de Estado lo hicieron en los 80\u201d"},"content":{"rendered":"<table style=\"width: 100%; background-color: #ffffff;\">\n<tbody>\n<tr valign=\"top\">\n<td valign=\"top\" width=\"500\">\n<h3><span style=\"color: #ffffff;\"><strong><span style=\"color: #ff0000;\"><img loading=\"lazy\" style=\"float: left; margin-right: 5px;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/joaquin_rivera.jpg\" alt=\"images\" height=\"258\" width=\"435\" \/>Joaqu\u00edn Mej\u00eda Rivera <!--more--> <\/span> <\/strong> <\/span><\/h3>\n<p><span style=\"color: #000000;\"><strong>Puesto Actual:<\/strong> <br \/>Coordinador del Departamento de DDHH para<\/span>&nbsp;<span style=\"text-decoration: underline;\"><strong> <a class=\"gkTooltip\" href=\"#\">ERIC<span class=\"customTooltip helpTooltip\"><em>ERIC<\/em>Equipo de Reflexi\u00f3n, Investigaci\u00f3n y Comunicaci\u00f3n<\/span> <\/a> <\/strong> <\/span><\/p>\n<hr \/>\n<p><span style=\"color: #000000;\">** Doctorado y Maestr\u00eda en Derechos Humanos de la Universidad Carlos III en Madrid<\/span><\/p>\n<p><span style=\"color: #000000;\"><br \/>** Ha participado en varios casos en la Comisi\u00f3n Interamericana de DDHH y la Corte Interamericana de DDHH.<\/span><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table style=\"width: 100%; height: 213px;\">\n<tbody>\n<tr valign=\"top\">\n<td valign=\"top\">\n<h3><img loading=\"lazy\" style=\"margin-top: 5px; margin-right: 30px; margin-bottom: 10px;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/1_5x5.jpg\" alt=\"images\" align=\"left\" height=\"78\" width=\"71\" \/><strong>\u00bfCu\u00e1l es el panorama general que ustedes se han encontrado despu\u00e9s de su \u00faltima visita? \u00bfHay dudas en torno al proceso de depuraci\u00f3n policial?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><span class=\"gkDropcap1\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><strong><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #ff0000;\"><span class=\"gkDropcap1\">R.<\/span><\/span><\/strong><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/strong> <\/span> <\/span> <\/span> <\/span> <\/span> <\/strong><\/p>\n<p>La Comisi\u00f3n Interventora ha lanzado varios mensajes simb\u00f3licos como puede ser la renuncia de la Directora de Fiscales, Daniela Ferrera, qui\u00e9n hab\u00eda jugado un papel muy importante para que en Honduras tengamos el MP que tenemos. El segundo mensaje simb\u00f3lico es que la Comisi\u00f3n ha comenzado a recibir a organizaciones civiles y esto genera alg\u00fan nivel de confianza por han dado a entender que son permeables a las opiniones de la ciudadan\u00eda.<\/p>\n<p>&nbsp;<br \/>En cuanto a la depuraci\u00f3n policial si tenemos una gran preocupaci\u00f3n porque en enero si parec\u00eda que las cosas pod\u00edan avanzar, no obstante hasta el momento hemos visto como el CONASIN (Consejo Nacional de Seguridad Interna) ha obstaculizado la elecci\u00f3n de una terna de funcionarios para que el Presidente de la Naci\u00f3n pueda elegir a las nuevas autoridades de la Direcci\u00f3n de Investigaci\u00f3n y Evaluaci\u00f3n de la Carrera Policial (DIECP); y hace casi un mes que el actual director y subdirector renunciaron a sus cargos y a\u00fan no se han adoptado ninguna decisi\u00f3n; con lo cual realmente es preocupante y hasta el momento la ciudadan\u00eda no est\u00e1 viendo si se est\u00e1n depurando o no; o qu\u00e9 medidas se tomar\u00e1n contra los depurados.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<h3><img loading=\"lazy\" style=\"margin-top: 5px; margin-right: 30px; margin-bottom: 10px; float: left;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/2_5x5.jpg\" alt=\"images\" height=\"78\" width=\"71\" \/><strong>Entonces, \u00bfel pueblo hondure\u00f1o puede confiar en el proceso de depuraci\u00f3n policial que se est\u00e1 llevando a cabo en estos momentos?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #ff0000;\"><span class=\"gkDropcap1\">R.<\/span><\/span> <\/strong> <\/span> <\/span> <\/span> <\/span> <\/span><\/p>\n<p>Una de las preocupaciones que nos dej\u00f3 la reuni\u00f3n con el Ministro es que nos advirti\u00f3 que no hab\u00eda que preocuparse por el nombramiento de los Altos Mandos del DIECP; qu\u00e9, seg\u00fan \u00e9l, hab\u00eda que preocuparse por los resultados y que ahora la DIECP estaba dando resultados; es decir, que el mismo director y subdirector que fueron interpelados en el Congreso y donde qued\u00f3 en evidencia que hab\u00edan fracasado dirigiendo est\u00e1 entidad, ahora est\u00e1n funcionando y haciendo su trabajo; con lo cual se lee entre l\u00edneas que el problema era el ministro anterior (Pompeyo Bonilla). Esto da a entender que este organismo no es independiente ni aut\u00f3nomo al Ministerio de Seguridad; lo cual significar\u00eda que el DIECP responde y es dependiente del Ministro de Seguridad; lo que genera una gran preocupaci\u00f3n porque estamos hablando de la sumisi\u00f3n de una instancia que, en teor\u00eda, deber\u00eda ser independiente.<\/p>\n<p>Ram\u00f3n Custodio, Comisionado Nacional de los Derechos Humanos, est\u00e1 defendiendo al actual director y subdirector de la DIECP, creemos que no hay voluntad pol\u00edtica para cambiarlos y esto implica que el poder ejecutivo, a trav\u00e9s del Ministerio de Seguridad y del CONASIN, est\u00e1n rest\u00e1ndole importancia al poder que tiene el Congreso para interpelar y aplazar a un funcionario. Adem\u00e1s,&nbsp; no se est\u00e1 respetando la figura del Presidente de la Rep\u00fablica qui\u00e9n acept\u00f3 la renuncia de estos dos funcionarios.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<h3><img loading=\"lazy\" style=\"margin-top: 5px; margin-right: 30px; margin-bottom: 10px; float: left;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/3_5x5.jpg\" alt=\"images\" height=\"78\" width=\"71\" \/><strong>Si el CONSAIN, y el Ministerio de Seguridad no est\u00e1n respetando la autoridad del Presidente de la Rep\u00fablica, \u00bfqui\u00e9n manda entonces en Honduras?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #ff0000;\"><span class=\"gkDropcap1\">R.<\/span><\/span> <\/strong> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span><\/p>\n<p>Tanto el Congreso- qui\u00e9n interpel\u00f3 e improb\u00f3 la conducta de estos dos funcionarios- como el Presidente de la Rep\u00fablica- qui\u00e9n acept\u00f3 la renuncia de ambos- tomaron una decisi\u00f3n, c\u00f3mo es posible que el CONASIN, que es un \u00f3rgano asesor de consulta del Ministerio de Seguridad, no tome esto en consideraci\u00f3n y no le d\u00e9 importancia a estos dos poderes del Estado debemos preguntarnos, \u00bfrealmente qui\u00e9n manda en este pa\u00eds?<\/p>\n<p>El CONSAIN lo que abduce es que ellos nunca han recibido formalmente por escrito la carta de renuncia, por lo cual esto tambi\u00e9n genera dudas porque implica que no creen en la palabra del Presidente de la Rep\u00fablica, que es la m\u00e1xima autoridad del Estado, qui\u00e9n afirm\u00f3 en p\u00fablico que acept\u00f3 la renuncia de estos dos funcionarios.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<h3><img loading=\"lazy\" style=\"margin-top: 5px; margin-right: 30px; margin-bottom: 10px; float: left;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/4_5x5.jpg\" alt=\"images\" height=\"78\" width=\"71\" \/><strong>\u00bfCree que la creaci\u00f3n de los TIGRES ser\u00eda positivo para Honduras?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #ff0000;\"><span class=\"gkDropcap1\">R.<\/span><\/span> <\/strong> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span><\/p>\n<p>Honduras necesita Fuerzas Especiales de \u00c9lite para reaccionar ante el crimen organizado y ante una violencia que es m\u00e1s grave de lo normal; no obstante esa unidad de \u00e9lite debe ser civil y no militar. La seguridad ciudadana es competencia de una polic\u00eda civil y democr\u00e1tica bajo mando civil; porque estamos hablando del trato con la ciudadan\u00eda. Y la seguridad nacional debe estar a cargo de militares capacitados para defender la soberan\u00eda y el territorio.<\/p>\n<p>Los militares en Honduras est\u00e1n ejerciendo funciones judiciales antes del 2002, con el gobierno de Maduro, han estado en las calles y si se miran las estad\u00edsticas del Observatorio de la Violencia el aumento ha sido imparable. Tener a los militares en las calles han sido un total fracaso, como toda la pol\u00edtica de seguridad en el pa\u00eds. Se le deben quitar las facultades policiales a los militares. Lo que deber\u00eda hacer el Estado, si de verdad hubiese voluntad pol\u00edtica, es tratar la violencia desde un enfoque amplio que tiene que ver con Derechos Humanos, con la reducci\u00f3n de pobreza,&nbsp; con oportunidades de empleo.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<h3><img loading=\"lazy\" style=\"margin-top: 5px; margin-right: 30px; margin-bottom: 10px; float: left;\" src=\"http:\/\/revistazo.com\/content\/wp-content\/uploads\/2020\/11\/5_5x5.jpg\" alt=\"images\" height=\"78\" width=\"71\" \/><strong>No hay casos emblem\u00e1ticos que puedan ser judicializados porque pr\u00e1cticamente no existe informaci\u00f3n dentro del Ministerio P\u00fablico, \u00bfpodr\u00edamos decir que las autoridades que han estado a cargo de la direcci\u00f3n del MP han borrado evidencias o no les han interesado investigar los casos?<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 10pt;\"><span style=\"color: #ff0000;\"><span style=\"color: #000000;\"><span style=\"font-size: 12pt;\"><strong><span style=\"color: #ff0000;\"><span class=\"gkDropcap1\">R.<\/span><\/span> <\/strong> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span> <\/span><\/p>\n<p>Hay diversas cuestiones, en Honduras tenemos una deuda hist\u00f3rica de impunidad. De acuerdo con el informe del Comisionado Nacional de Derechos Humanos se refleja, claramente, que hasta el momento no hay nadie investigado, judicializado o condenado por la violaciones a los Derechos Humanos que se cometieron en los a\u00f1os &#8217;80; y luego vemos que todas las violaciones cometidas durante el Golpe de Estado, y que fueron documentadas- a trav\u00e9s de la Comisi\u00f3n de la Verdad y la Reconciliaci\u00f3n- tampoco nadie ha sido condenado; y una de las caracter\u00edsticas de los violadores de los Derechos Humanos durante el golpe es que son las mismas que durante los 80. Esto significa que muchos de los que cometieron el Golpe de Estado son los mismos que violaron derechos en los &#8217;80; y por tanto, ese c\u00edrculo de impunidad genera que se sigan cometiendo estas violaciones.<\/p>\n<p>Nos preocupaba que la Comisi\u00f3n Interventora dijera que existen casos pero que la investigaci\u00f3n ha sido tan terrible que es casi imposible poder construir algo para poder presentarlo ante los Tribunales de la Republica. Nos preocupa que la Comisi\u00f3n Interventora se\u00f1ale eso, porque por un lado puede tratarse de presiones pol\u00edticas para que no presente ning\u00fan caso o, por otro lado, puede ser que los abogados no han estado actualiz\u00e1ndose de lo que est\u00e1 sucediendo sobre todo en el tema de Derechos Humanos donde figuras que eran tradicionales ahora no son intocables.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Joaqu\u00edn Mej\u00eda Rivera<\/p>\n","protected":false},"author":4,"featured_media":7665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[29],"tags":[],"_links":{"self":[{"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/posts\/642"}],"collection":[{"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":0,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/media\/7665"}],"wp:attachment":[{"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/revistazo.com\/content\/wp-json\/wp\/v2\/tags?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}